{"id":556,"date":"2012-07-30T13:41:23","date_gmt":"2012-07-30T01:41:23","guid":{"rendered":"http:\/\/limestonehills.co.nz\/store\/express\/"},"modified":"2012-07-30T13:41:23","modified_gmt":"2012-07-30T01:41:23","slug":"express","status":"publish","type":"page","link":"https:\/\/limestonehills.co.nz\/Wordpress\/store\/express\/","title":{"rendered":"Express"},"content":{"rendered":"<p>[express]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[express]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":437,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-556","page","type-page","status-publish","hentry"],"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/limestonehills.co.nz\/Wordpress\/wp-json\/wp\/v2\/pages\/556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limestonehills.co.nz\/Wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/limestonehills.co.nz\/Wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/limestonehills.co.nz\/Wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/limestonehills.co.nz\/Wordpress\/wp-json\/wp\/v2\/comments?post=556"}],"version-history":[{"count":0,"href":"https:\/\/limestonehills.co.nz\/Wordpress\/wp-json\/wp\/v2\/pages\/556\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/limestonehills.co.nz\/Wordpress\/wp-json\/wp\/v2\/pages\/437"}],"wp:attachment":[{"href":"https:\/\/limestonehills.co.nz\/Wordpress\/wp-json\/wp\/v2\/media?parent=556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}